{"id":21407,"date":"2017-03-24T18:53:24","date_gmt":"2017-04-05T09:08:55","guid":{"rendered":"http:\/\/www.simplysteelform.com\/?post_type=product&#038;p=21407\/"},"modified":"2022-04-11T02:42:28","modified_gmt":"2022-04-11T00:42:28","slug":"lounge-chair-ottoman-charles-eames","status":"publish","type":"product","link":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/","title":{"rendered":"Lounge chair y ottoman"},"content":{"rendered":"<div class=\"row\"  id=\"row-787772358\">\n\n\n\t<div id=\"col-650991468\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-shadow-2 box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"434\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-nero.jpg\" class=\"attachment- size-\" alt=\"Aniline leather black\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-nero.jpg 455w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-nero-300x286.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-nero-247x236.jpg 247w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<p>NERO<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-56861513\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-shadow-2 box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"436\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-cioccolato.jpg\" class=\"attachment- size-\" alt=\"Aniline leather dark brown\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-cioccolato.jpg 455w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-cioccolato-300x287.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-cioccolato-247x237.jpg 247w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<p>CIOCCOLATO<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1979529922\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-shadow-2 box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"438\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-cognac.jpg\" class=\"attachment- size-\" alt=\"Aniline leather tan\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-cognac.jpg 455w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-cognac-300x289.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-cognac-247x238.jpg 247w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<p>COGNAC<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1526694940\" class=\"col medium-3 small-6 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-shadow-2 box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"440\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-crema.jpg\" class=\"attachment- size-\" alt=\"Aniline leather cream\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-crema.jpg 455w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-crema-300x290.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/dani-lord-crema-247x239.jpg 247w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<p>CREMA<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 90px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"137\" height=\"138\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/carbon-footprint.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/carbon-footprint.png 137w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/carbon-footprint-100x100.png 100w\" sizes=\"(max-width: 137px) 100vw, 137px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3><strong>Piel de anilina sostenible<\/strong><\/h3>\n<p>Este producto \u00a0esta fabricado usando una piel completamente libre de sustancias nocivas. La produce la prestigiosa curtidur\u00eda Italiana DANI SpA.\u00a0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-1147095077\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1147095077 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1494139096\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1494139096 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"message-box relative dark\" style=\"padding-top:15px;padding-bottom:15px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(252, 0, 0);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n<div class=\"row align-middle align-center\"  id=\"row-602143745\">\n\n\t<div id=\"col-1439430076\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h1 style=\"text-align: center;\"><span style=\"font-size: 150%;\">Eames\u00a0designed:\u00a0Lounge chair y ottoman<\/span><\/h1>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<\/div><\/div><\/div>\n\t<div id=\"gap-104350923\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-104350923 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-large align-center\"  id=\"row-701271669\">\n\n\t<div id=\"col-769103974\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1833293465\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"458\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_lounge_chair_technical_drawing-1024x460.jpg\" class=\"attachment-large size-large\" alt=\"Charles Eames Lounge Chair technical drawing\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_lounge_chair_technical_drawing-1024x460.jpg 1024w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_lounge_chair_technical_drawing-300x135.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_lounge_chair_technical_drawing-768x345.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_lounge_chair_technical_drawing-247x111.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_lounge_chair_technical_drawing-510x229.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_lounge_chair_technical_drawing-500x225.jpg 500w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_lounge_chair_technical_drawing.jpg 1336w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1833293465 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>La nueva talla MAXI con <strong>altura total de 92cm<\/strong> oferece a\u00fan mas conforto para las personas altas.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_110642057\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"287\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_ottoman_technical_drawing-1024x288.jpg\" class=\"attachment-large size-large\" alt=\"Lounge Ottoman technical drawing\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_ottoman_technical_drawing-1024x288.jpg 1024w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_ottoman_technical_drawing-300x85.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_ottoman_technical_drawing-768x216.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_ottoman_technical_drawing-247x70.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_ottoman_technical_drawing-510x144.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_ottoman_technical_drawing-500x141.jpg 500w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames_ottoman_technical_drawing.jpg 1200w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_110642057 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1093977035\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"p1\"><strong>Lounge chair y ottoman\u00a0<\/strong><\/h2>\n<p class=\"p1\">Patas fabricadas en aluminio lacado negro. Bordes superiores pulidos con un alto brillo.<\/p>\n<p class=\"p1\">Cuerpo de madera moldeada en palisandro chapeado.<\/p>\n<p class=\"p1\">Tapicer\u00eda hecha con espuma, algod\u00f3n sint\u00e9tico y cubierta con piel de anilina respetuosa con el medio ambiente.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<style>\n#row-701271669 > .col > .col-inner {\n  padding: 20px 20px 20px 20px;\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-286094645\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-286094645 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"message-box relative dark\" style=\"padding-top:15px;padding-bottom:15px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(255, 255, 255);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\r\n\r\n<div class=\"row align-middle align-center\"  id=\"row-1133784313\">\r\n\r\n\n\t<div id=\"col-893703054\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<h2 style=\"text-align: center;\"><span style=\"font-size: 200%;\">Reproducci\u00f3n de la m\u00e1s gran calidad<\/h2>\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n<\/div><\/div><\/div>\r\n\t<div id=\"gap-19859233\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-19859233 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1904340294\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"408\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER-1500x600.jpg\" class=\"attachment-large size-large\" alt=\"Charles Eames Lounge Chair\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER-1500x600.jpg 1500w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER-300x120.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER-768x307.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER-247x99.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER-510x204.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER-500x200.jpg 500w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER-1024x410.jpg 1024w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-EYECATCHER.jpg 2000w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1904340294 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1216926743\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1216926743 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_141441937\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_141441937 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-2064317279\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2064317279 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<p class=\"p1\" style=\"text-align: justify;\">La Lounge Chair y Ottoman brillantemente dise\u00f1ados por Charles Eames son el ep\u00edtome de que todo es c\u00f3modo (y lujorioso) en un simple silla o butaca.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Nuestra versi\u00f3n de la silla de sal\u00f3n coincide con el dise\u00f1o original construido en 1956 para Herman Miller.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">En el proceso, hemos mejorado los puntos d\u00e9biles del original, creando una Lounge Chair y Ottoman que supera al original en calidad. \u00a1El plagio definitivamente no es parte de nuestro vocabulario!<\/p>\n\t<section class=\"section\" id=\"section_468869849\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<blockquote>\n<p class=\"lead\"><span class=\"s1\">\u00a1No hay nada peor que una mala copia!<\/span><\/p>\n<p class=\"lead\"><span class=\"s1\">Con nuestra reproducci\u00f3n de Lounge Chair y Ottoman obtendr\u00e1 un mueble exclusivo y de gran calidad.\u00a0<\/span><\/p>\n<\/blockquote>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_468869849 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1370100959\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1370100959 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"message-box relative dark\" style=\"padding-top:15px;padding-bottom:15px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(254, 0, 0);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\r\n\r\n<div class=\"row align-middle align-center\"  id=\"row-2113631032\">\r\n\r\n\n\t<div id=\"col-2075270293\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<h2 style=\"text-align: center;\"><span style=\"font-size: 140%;\">Prestamos la mayor atenci\u00f3n a los detalles<\/h2>\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n<\/div><\/div><\/div>\r\n\t<div id=\"gap-36708288\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-36708288 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-bottom\"  id=\"row-839149449\">\n\n\t<div id=\"col-122252062\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1832659621\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"800\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-leder.jpg\" class=\"attachment-large size-large\" alt=\"Charles Eames Lounge Chair leather\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-leder.jpg 1000w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-leder-300x240.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-leder-768x614.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-leder-247x198.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-leder-510x408.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-leder-500x400.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1832659621 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1851264166\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-left\" style=\"max-width:520px;\" >\n\t\t\t\n\t\t\t\n<h3><strong>Cuero como la seda<\/strong><\/h3>\n<p>Charles Eames deseaba que su silla fuera parecida al aspecto de un guante de b\u00e9isbol bien gastado. Es decir, fabricado con un cuero tan suave y fino como los empleados para fabricar dichos guantes.<\/p>\n<p>Es por eso que hemos optado por cubrir nuestra versi\u00f3n de este silla cl\u00e1sica con la piel m\u00e1s suave en un curtido en anilina. El grano natural del cuero es sedoso-liso y cubre la tapicer\u00eda en pliegues suaves.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1851264166 > .col-inner {\n  padding: 5% 5% 5% 5%;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-452819913\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-452819913 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-bottom\"  id=\"row-1501084565\">\n\n\t<div id=\"col-1695472598\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-left\" style=\"max-width:520px;\" >\n\t\t\t\n\t\t\t\n<h3><strong>Madera tropical cuidadosamente seleccionada<\/strong><\/h3>\n<p>A nuestros ojos, el grano pronunciado de la chapa de palisandro original complementa perfectamente la Lounge Chair.<\/p>\n<p>Usted puede tener constancia cuando selecciona nuestro palisandro que este se acerca m\u00e1s a la secoya usada en el original. Nuestro palisandro esta cultivado en Bolivia y Brasil bajo las m\u00e1s rigurosas condiciones.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1695472598 > .col-inner {\n  padding: 5% 5% 5% 5%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1625073688\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1613216751\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"800\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-wood.jpg\" class=\"attachment-large size-large\" alt=\"Charles Eames Lounge Chair wood\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-wood.jpg 1000w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-wood-300x240.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-wood-768x614.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-wood-247x198.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-wood-510x408.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-wood-500x400.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1613216751 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1785401138\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1785401138 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-bottom\"  id=\"row-748378797\">\n\n\t<div id=\"col-1410665398\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1874453143\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"800\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-cushion.jpg\" class=\"attachment-large size-large\" alt=\"Charles Eames Lounge Chair cushion filling\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-cushion.jpg 1000w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-cushion-300x240.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-cushion-768x614.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-cushion-247x198.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-cushion-510x408.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-cushion-500x400.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1874453143 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1003011274\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-left\" style=\"max-width:520px;\" >\n\t\t\t\n\t\t\t\n<h3><strong>Relax con estilo<\/strong><\/h3>\n<p>Los cojines est\u00e1n llenos de varias capas de espuma y algod\u00f3n sint\u00e9tico. Esto da a la tapicer\u00eda de nuestra Lounge Chair un aspecto m\u00e1s lujoso y decorativo.<\/p>\n<p>Nuestra silla de sal\u00f3n es realmente tan c\u00f3moda como parece.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1003011274 > .col-inner {\n  padding: 5% 5% 5% 5%;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1543294917\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1543294917 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-bottom\"  id=\"row-1281984221\">\n\n\t<div id=\"col-1947303537\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-left\" style=\"max-width:520px;\" >\n\t\t\t\n\t\t\t\n<h3><strong>Un solo molde<\/strong><\/h3>\n<p>Fiel al original, las patas de nuestra Lounge Chair se hicieron para que coincida con el original de Herman Miller. La superficie superior del perfil de aluminio fundido a presi\u00f3n, lacada en negro y pulida con un acabado de alto brillo.<\/p>\n<p>Los pies ajustables del acero inoxidable permiten que usted ajuste r\u00e1pidamente su silla a las superficies irregulares.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1947303537 > .col-inner {\n  padding: 5% 5% 5% 5%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1415689073\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_538434153\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"800\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-foot.jpg\" class=\"attachment-large size-large\" alt=\"Charles Eames Lounge Chair base\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-foot.jpg 1000w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-foot-300x240.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-foot-768x614.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-foot-247x198.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-foot-510x408.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-foot-500x400.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_538434153 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1490619768\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1490619768 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-bottom\"  id=\"row-1236287578\">\n\n\t<div id=\"col-314272895\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2058115208\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"800\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-bushings.jpg\" class=\"attachment-large size-large\" alt=\"Charles Eames Lounge Chair bushings\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-bushings.jpg 1000w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-bushings-300x240.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-bushings-768x614.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-bushings-247x198.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-bushings-510x408.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-bushings-500x400.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2058115208 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-686290260\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-left\" style=\"max-width:520px;\" >\n\t\t\t\n\t\t\t\n<h3><strong>Construcci\u00f3n robusta<\/strong><\/h3>\n<p>Uno de los puntos d\u00e9biles en el dise\u00f1o original es la conexi\u00f3n giratoria entre la carcasa del asiento y la base. Es por eso que hemos optado por reforzar este montaje con casquillos de lat\u00f3n macizo. La estabilidad de nuestro ensamblado significa que su silla de sal\u00f3n no oscilar\u00e1, incluso despu\u00e9s de varios a\u00f1os.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-686290260 > .col-inner {\n  padding: 5% 5% 5% 5%;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1911300266\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1911300266 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-bottom\"  id=\"row-692217236\">\n\n\t<div id=\"col-1981577800\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner text-left\" style=\"max-width:520px;\" >\n\t\t\t\n\t\t\t\n<h3><strong>Doble soporte<\/strong><\/h3>\n<p>Tambi\u00e9n pensamos que abordar\u00edamos otro punto d\u00e9bil en el dise\u00f1o original, los soportes amortiguados.<\/p>\n<p>Nuestros soportes amortiguados que conectan el asiento y el respaldo, est\u00e1n pegados y tambi\u00e9n atornillados en la madera. Utilizando un grado ligeramente m\u00e1s grueso de madera contrachapada, podemos sujetar los soportes con 10 tornillos peque\u00f1os.<\/p>\n<p>Esta conexi\u00f3n ha dado paso en muchas versiones posteriores de la silla de sal\u00f3n.<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-1981577800 > .col-inner {\n  padding: 5% 5% 5% 5%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-690506313\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_164761104\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"800\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-wooden-shell-ear.jpg\" class=\"attachment-large size-large\" alt=\"Charles Eames Lounge Chair ears\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-wooden-shell-ear.jpg 1000w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-wooden-shell-ear-300x240.jpg 300w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-wooden-shell-ear-768x614.jpg 768w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-wooden-shell-ear-247x198.jpg 247w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-wooden-shell-ear-510x408.jpg 510w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/lounge-chair-wooden-shell-ear-500x400.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_164761104 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-227802463\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-227802463 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1927891491\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1927891491 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-2036309890\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2036309890 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-223852912\">\n\n\n\t<div id=\"col-289736438\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 120px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/120.png\" class=\"attachment-medium size-medium\" alt=\"120% refund policy\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/120.png 120w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/120-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3><strong>Le devolvemos el 120%!<\/strong><\/h3>\n<p>Si encuentra una reproducci\u00f3n con mejor calidad que la nuestra, h\u00e1znoslo saber.<\/p>\n<p>Nosotros no tan solo le devolveremos su dinero, adem\u00e1s le a\u00f1adiremos un 20% extra por ayudarnos a mejorar nuestros productos.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2070566024\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 120px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/100.png\" class=\"attachment-medium size-medium\" alt=\"100% Quality\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/100.png 120w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/100-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3><strong>100% Calidad Original!<\/strong><\/h3>\n<p>Nosotros tomamos cuidado hasta el m\u00e1s m\u00ednimo detalle.<\/p>\n<p>Nuestros muebles est\u00e1n fabricados con los mismos altos standards de calidad de otros productos mucho m\u00e1s caros.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2110689781\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 120px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/10.png\" class=\"attachment-medium size-medium\" alt=\"10 Year Guarantee\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/10.png 120w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/10-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<h3><strong>10 A\u00f1os de garant\u00eda!<\/strong><\/h3>\n<p>Nuestros muebles est\u00e1n construidos para durar toda la vida.<\/p>\n<p>Durante los primeros 10 a\u00f1os nosotros reemplazamos o reparamos cualquier art\u00edculo el cual este da\u00f1ado debido a un fallo del material o de fabricaci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1321486365\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1321486365 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 class=\"accordion_title\">\u00bfTiene usted preguntas?<\/h3><div class=\"accordion\" rel=\"\">\n\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>Aqu\u00ed tiene algunas respuestas<\/span><\/a><div class=\"accordion-inner\">\n\n<h3><strong>\u00bfSon nuestros muebles aut\u00e9nticos?<\/strong><\/h3>\n<p>Estamos construyendo excelentes reproducciones modernas de dise\u00f1os cl\u00e1sicos de la \u00e9poca Bauhaus a mediados de siglo, que coinciden absolutamente con los m\u00e1s altos est\u00e1ndares de calidad de los productos que se comercializan como los \u00fanicos \"aut\u00e9nticos\".<\/p>\n<p>Estamos hablando de dise\u00f1os de hasta 90 a\u00f1os de edad que han sido producidos por diferentes empresas a trav\u00e9s de las d\u00e9cadas. As\u00ed que los materiales y tecnolog\u00edas de producci\u00f3n han mejorado mucho desde los primeros prototipos.<\/p>\n<p>Llamar a cualquier versi\u00f3n moderna tal como \"aut\u00e9ntico\" no es m\u00e1s que un enga\u00f1o de marketing.<\/p>\n<p>\u00a0<\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:200px;background-color:rgb(255, 0, 0);\"><\/div><\/div>\n\n<h3><strong>\u00bfCu\u00e1nto cuesta el env\u00edo?<\/strong><\/h3>\n<p>Dentro de Europa:<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 120%;\">\u00a1El env\u00edo es gratuito!<\/span><\/strong><\/p>\n<p>Am\u00e9rica y resto del mundo:<\/p>\n<p><strong><span style=\"font-size: 120%;\">Env\u00edo es gratuito para cualquier pedido igual y superior a 3,000 $<\/span><\/strong><\/p>\n<p>Para cantidades inferiores, simplemente env\u00edenos su pedido y nos pondremos en contacto con usted con el precio exacto.<\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:200px;background-color:rgb(255, 0, 0);\"><\/div><\/div>\n\n<h3><strong>\u00bfEs legal?<\/strong><\/h3>\n<p>Muebles de m\u00e1s de 50 a\u00f1os de edad, no est\u00e1n protegidos por derechos en la mayor\u00eda de pa\u00edses del mundo.<\/p>\n<p>Las excepciones son aplicables para algunos pa\u00edses europeos, pero ya que los bienes pueden viajar libremente dentro de Europa y no hay fronteras aduaneras, son libres de ordenar de nosotros lo que quieran.<\/p>\n<p>\u00a0<\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:200px;background-color:rgb(255, 0, 0);\"><\/div><\/div>\n\n<h3><strong>M\u00e9todos de pago<\/strong><\/h3>\n<p>La forma m\u00e1s segura y m\u00e1s f\u00e1cil es usar su tarjeta de cr\u00e9dito.<\/p>\n<p>Sin embargo vamos a aceptar transferencias electr\u00f3nicas si no tiene una tarjeta de cr\u00e9dito por mayores cantidades en las compras corporativas.<\/p>\n<p>\u00a0<\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:200px;background-color:rgb(250, 0, 0);\"><\/div><\/div>\n\n<h3><strong>\u00a1He visto este art\u00edculo por menos!<\/strong><\/h3>\n<p>\u00a1Sin duda ninguno de los nuestros! Hay un gran n\u00famero de copias baratas que sin embargo se parecen algo, pero ciertamente no lo son.<\/p>\n<p>Nuestro mobiliario est\u00e1 fabricado a mano cuidadosamente en Italia utilizando los mejores materiales. Teniendo en cuenta esto, nuestras piezas son de un valor incalculable en\u00a0dinero.\u00a0<\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:200px;background-color:rgb(255, 0, 0);\"><\/div><\/div>\n\n<h3><strong>\u00bfPuedo obtener un descuento?<\/strong><\/h3>\n<p class=\"p1\">Claro, si usted quiere pedir varios art\u00edculos. Cuanto m\u00e1s ordene, m\u00e1s alto ser\u00e1 el descuento.<\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:200px;background-color:rgb(255, 0, 0);\"><\/div><\/div>\n\n<h3><strong>\u00bfCu\u00e1nto tiempo tomar\u00e1 la entrega?<\/strong><\/h3>\n<p>Nuestro mobiliario est\u00e1 hecho a mano hecho a la medida, por lo que no puede competir con la velocidad de Amazon &amp; Co.<\/p>\n<p>En t\u00e9rminos generales, nuestros productos est\u00e1n listos para el env\u00edo dentro de 3 a 4 semanas a partir de la fecha de pedido.<\/p>\n<p>El env\u00edo en s\u00ed dura una semana dentro de Europa. \u00a1El env\u00edo al extranjero por v\u00eda a\u00e9rea lleva s\u00f3lo 3 d\u00edas!<\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:200px;background-color:rgb(255, 0, 0);\"><\/div><\/div>\n\n\t<div id=\"gap-98130940\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-98130940 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"uppercase\">\u00bfotras preguntas?<\/h2>\n<h3 class=\"thin-font\">Por favor escr\u00edbanos, nos pondremos en contacto con usted tan pronto como sea posible<\/h3>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4-o1\" lang=\"de-DE\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/product\/21407#wpcf7-f4-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.8\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Your Name (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Your Email (required)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Subject<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Your Message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-539\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-539\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I am not a robot<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"quiz-408\"><label><span class=\"wpcf7-quiz-label\">5+2-7 = ?<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz-408\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz-408\" value=\"910056aaba06950c294efa7186338df9\" \/><\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n<\/div><\/div>\n\n<\/div>\n\t<div id=\"gap-606129463\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-606129463 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"message-box relative dark\" style=\"padding-top:15px;padding-bottom:15px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(254, 0, 0);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\r\n\r\n<div class=\"row align-middle align-center\"  id=\"row-983933622\">\r\n\r\n\n\t<div id=\"col-1692472685\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<h2 style=\"text-align: center;\"><span style=\"font-size: 140%;\">30.000 Clientes satisfechos en 20 A\u00f1os!<\/span><\/h2>\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n<\/div><\/div><\/div>\r\n\t<div id=\"gap-350487928\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-350487928 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" ><\/div><\/div>\n<div class=\"row align-equal row-box-shadow-2 row-box-shadow-5-hover\"  id=\"row-1476036090\">\n\n\t<div id=\"col-1679504407\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-img testimonial-image circle\" style=\"width: 121px\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-1-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-1-1-150x150.jpg 150w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-1-1-100x100.jpg 100w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-1-1.jpg 182w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>        <\/div>\n                <div class=\"icon-box-text p-last-0\">\n          <div class=\"star-rating\"><span style=\"width:100%\"><strong class=\"rating\"><\/strong><\/span><\/div>  \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n<p>Excellent workmanship! You truly lived up to your promise.<\/p>\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">Paul Russe<\/strong>\n             <span class=\"testimonial-name-divider\"> \/ <\/span>             <span class=\"testimonial-company test_company\">Amsterdam<\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1537494432\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-img testimonial-image circle\" style=\"width: 121px\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-3-150x150.jpg 150w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-3-100x100.jpg 100w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-3.jpg 200w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>        <\/div>\n                <div class=\"icon-box-text p-last-0\">\n          <div class=\"star-rating\"><span style=\"width:100%\"><strong class=\"rating\"><\/strong><\/span><\/div>  \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n<p>Absolutely love the Eames Lounge in my studio. Very good quality, I am impressed.<\/p>\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">Igor Russell<\/strong>\n             <span class=\"testimonial-name-divider\"> \/ <\/span>             <span class=\"testimonial-company test_company\">Prague<\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-838755351\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-img testimonial-image circle\" style=\"width: 121px\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-2-150x150.jpg 150w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-2-100x100.jpg 100w, https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/testimonial-2.jpg 200w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>        <\/div>\n                <div class=\"icon-box-text p-last-0\">\n          <div class=\"star-rating\"><span style=\"width:100%\"><strong class=\"rating\"><\/strong><\/span><\/div>  \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n<p>The leather truly feels wonderful! Your lounge chair is definitely more than worth the\u00a0price.<\/p>\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">Thilo Schmidt<\/strong>\n             <span class=\"testimonial-name-divider\"> \/ <\/span>             <span class=\"testimonial-company test_company\">Bremen<\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1476036090 > .col > .col-inner {\n  padding: 30px 30px 30px 30px;\n}\n<\/style>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"is-divider divider clearfix\" ><\/div>\n<p>\u2705\u00a0Envio gratuito<br \/>\n\u2705\u00a0Fabricado en Italia<br \/>\n\u2705\u00a0Listo para entrega en 20 d\u00edas <\/p>\n<div class=\"is-divider divider clearfix\" ><\/div>\n","protected":false},"featured_media":19565,"template":"","meta":{"qubely_global_settings":"","qubely_interactions":""},"product_cat":[118],"product_tag":[],"class_list":{"0":"post-21407","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-charles-eames-es","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eames Lounge Chair y Ottoman | steelform les presenta los cl\u00e1sicos del dise\u00f1o<\/title>\n<meta name=\"description\" content=\"Reedici\u00f3n aut\u00e9ntica del Lounge Chair y Ottoman por Charles Eames fabricada en Italia usando los mejores materiales. Muebles de gran calidad desde el 1997\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eames Lounge Chair y Ottoman | steelform les presenta los cl\u00e1sicos del dise\u00f1o\" \/>\n<meta property=\"og:description\" content=\"Reedici\u00f3n aut\u00e9ntica del Lounge Chair y Ottoman por Charles Eames fabricada en Italia usando los mejores materiales. Muebles de gran calidad desde el 1997\" \/>\n<meta property=\"og:url\" content=\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/\" \/>\n<meta property=\"og:site_name\" content=\"steelform | the best reproductions of modern classic designer furniture\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-11T00:42:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-ottoman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/\",\"url\":\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/\",\"name\":\"Eames Lounge Chair y Ottoman | steelform les presenta los cl\u00e1sicos del dise\u00f1o\",\"isPartOf\":{\"@id\":\"https:\/\/steelform.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-ottoman.jpg\",\"datePublished\":\"2017-04-05T09:08:55+00:00\",\"dateModified\":\"2022-04-11T00:42:28+00:00\",\"description\":\"Reedici\u00f3n aut\u00e9ntica del Lounge Chair y Ottoman por Charles Eames fabricada en Italia usando los mejores materiales. Muebles de gran calidad desde el 1997\",\"breadcrumb\":{\"@id\":\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#primaryimage\",\"url\":\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-ottoman.jpg\",\"contentUrl\":\"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-ottoman.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/steelform.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/steelform.com\/es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lounge chair y ottoman\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/steelform.com\/fr\/#website\",\"url\":\"https:\/\/steelform.com\/fr\/\",\"name\":\"steelform | the best reproductions of modern classic designer furniture\",\"description\":\"true to original premium quality reproduction from Italy.\",\"publisher\":{\"@id\":\"https:\/\/steelform.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/steelform.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/steelform.com\/fr\/#organization\",\"name\":\"steelform.com\",\"url\":\"https:\/\/steelform.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/steelform.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/steelform.com\/wp-content\/uploads\/revslider\/corbusier-lc21-de\/steelform-logo-large-1.jpg\",\"contentUrl\":\"https:\/\/steelform.com\/wp-content\/uploads\/revslider\/corbusier-lc21-de\/steelform-logo-large-1.jpg\",\"width\":588,\"height\":588,\"caption\":\"steelform.com\"},\"image\":{\"@id\":\"https:\/\/steelform.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eames Lounge Chair y Ottoman | steelform les presenta los cl\u00e1sicos del dise\u00f1o","description":"Reedici\u00f3n aut\u00e9ntica del Lounge Chair y Ottoman por Charles Eames fabricada en Italia usando los mejores materiales. Muebles de gran calidad desde el 1997","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/","og_locale":"es_ES","og_type":"article","og_title":"Eames Lounge Chair y Ottoman | steelform les presenta los cl\u00e1sicos del dise\u00f1o","og_description":"Reedici\u00f3n aut\u00e9ntica del Lounge Chair y Ottoman por Charles Eames fabricada en Italia usando los mejores materiales. Muebles de gran calidad desde el 1997","og_url":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/","og_site_name":"steelform | the best reproductions of modern classic designer furniture","article_modified_time":"2022-04-11T00:42:28+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-ottoman.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/","url":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/","name":"Eames Lounge Chair y Ottoman | steelform les presenta los cl\u00e1sicos del dise\u00f1o","isPartOf":{"@id":"https:\/\/steelform.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#primaryimage"},"image":{"@id":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#primaryimage"},"thumbnailUrl":"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-ottoman.jpg","datePublished":"2017-04-05T09:08:55+00:00","dateModified":"2022-04-11T00:42:28+00:00","description":"Reedici\u00f3n aut\u00e9ntica del Lounge Chair y Ottoman por Charles Eames fabricada en Italia usando los mejores materiales. Muebles de gran calidad desde el 1997","breadcrumb":{"@id":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#primaryimage","url":"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-ottoman.jpg","contentUrl":"https:\/\/steelform.com\/wp-content\/uploads\/2017\/03\/eames-lounge-chair-ottoman.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/steelform.com\/es\/produkt\/lounge-chair-ottoman-charles-eames\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/steelform.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/steelform.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Lounge chair y ottoman"}]},{"@type":"WebSite","@id":"https:\/\/steelform.com\/fr\/#website","url":"https:\/\/steelform.com\/fr\/","name":"steelform | the best reproductions of modern classic designer furniture","description":"true to original premium quality reproduction from Italy.","publisher":{"@id":"https:\/\/steelform.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/steelform.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/steelform.com\/fr\/#organization","name":"steelform.com","url":"https:\/\/steelform.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/steelform.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/steelform.com\/wp-content\/uploads\/revslider\/corbusier-lc21-de\/steelform-logo-large-1.jpg","contentUrl":"https:\/\/steelform.com\/wp-content\/uploads\/revslider\/corbusier-lc21-de\/steelform-logo-large-1.jpg","width":588,"height":588,"caption":"steelform.com"},"image":{"@id":"https:\/\/steelform.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/steelform.com\/es\/wp-json\/wp\/v2\/product\/21407"}],"collection":[{"href":"https:\/\/steelform.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/steelform.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steelform.com\/es\/wp-json\/wp\/v2\/media\/19565"}],"wp:attachment":[{"href":"https:\/\/steelform.com\/es\/wp-json\/wp\/v2\/media?parent=21407"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/steelform.com\/es\/wp-json\/wp\/v2\/product_cat?post=21407"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/steelform.com\/es\/wp-json\/wp\/v2\/product_tag?post=21407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}